{"id":15411,"date":"2025-06-13T14:45:46","date_gmt":"2025-06-13T18:45:46","guid":{"rendered":"https:\/\/www.virginiawestern.edu\/academics-new\/?page_id=15411&#038;preview_id=15411"},"modified":"2026-03-17T16:18:21","modified_gmt":"2026-03-17T20:18:21","slug":"grading-clinical","status":"publish","type":"page","link":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/","title":{"rendered":"Grading &amp; Clinical Requirements"},"content":{"rendered":"<style>.kb-row-layout-id15411_ee0c1a-8a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15411_ee0c1a-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15411_ee0c1a-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(74% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(26% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id15411_ee0c1a-8a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15411_ee0c1a-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15411_ee0c1a-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15411_ee0c1a-8a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column15411_2abd35-57 > .kt-inside-inner-col,.kadence-column15411_2abd35-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15411_2abd35-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15411_2abd35-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15411_2abd35-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15411_2abd35-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15411_2abd35-57{position:relative;}@media all and (max-width: 1024px){.kadence-column15411_2abd35-57 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15411_2abd35-57 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column15411_2abd35-57\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Grading Information<\/h2>\n\n\n\n<p>Students must maintain a grade of C or better in all program elective courses and all Radiation Oncology courses, and an overall GPA of 2.0 to continue in the program and graduate. All didactic Radiation Oncology classes require a 77 average to remain in the program. All clinical courses require an 81 overall average to remain in the program.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Didactic Courses<\/h3>\n\n\n\n<p>Grades for&nbsp;didactic Radiation Oncology courses&nbsp;will have the following grading scale:<\/p>\n\n\n\n<p><strong>Grading Format<\/strong><\/p>\n\n\n\n<p>A = 93-100<br>B = 85-92<br>C = 77-84<br>F = &lt;76<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Clinical Courses<\/h3>\n\n\n\n<p>Grades for&nbsp;clinical Radiation Oncology courses&nbsp;will have the following grading scale:<\/p>\n\n\n\n<p><strong>Grading Format<\/strong><\/p>\n\n\n\n<p>A = 95-100<br>B = 88-94<br>C = 81-87<br>F = &lt;80<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Receiving less than a C grade in any Radiation Oncology course will prohibit the student from continuation in the Program. If the student fails to maintain a C or better in program elective courses during the program, the student may take the course in the next semester or may need to extend the program completion.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Clinical Requirements<\/h2>\n\n\n\n<p>Admission to any clinical education site is contingent upon receipt and approval of the following:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Physical exam by a medical physician to include basic blood test<\/li>\n\n\n\n<li>Essential Function form completed by medical physician<\/li>\n\n\n\n<li>Completed Immunization and\/or titer record (MMR, Hep B, Tdap, Varicella Zoster, Polio) current clinical requirements<\/li>\n\n\n\n<li>Completed PPD for TB screening (initial 2 step screening)<\/li>\n\n\n\n<li>Influenza vaccination<\/li>\n\n\n\n<li>American Heart Association Healthcare Provider CPR certification<\/li>\n\n\n\n<li>Negative criminal background check<\/li>\n\n\n\n<li>Negative drug screen<\/li>\n\n\n\n<li>COVID screening and negative test<\/li>\n\n\n\n<li>Completion and approval of site-specific clinical education department requirements<\/li>\n<\/ul>\n\n\n\n<p><strong>Note:<\/strong>&nbsp;Successful completion of clinical requirements does not guarantee admission to the program. Successful completion of academic requirements and acceptance into the program does not guarantee admission into the clinical site. Students must successfully complete both academic and clinical requirements to be a student in the program and progress in the program.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column15411_b2230a-2d > .kt-inside-inner-col,.kadence-column15411_b2230a-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15411_b2230a-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15411_b2230a-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column15411_b2230a-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15411_b2230a-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15411_b2230a-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column15411_b2230a-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15411_b2230a-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column15411_b2230a-2d\"><div class=\"kt-inside-inner-col\"><style>.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col,.kadence-column15411_71e16f-d6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{background-color:#18284a;}.kadence-column15411_71e16f-d6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15411_71e16f-d6, .kadence-column15411_71e16f-d6 h1, .kadence-column15411_71e16f-d6 h2, .kadence-column15411_71e16f-d6 h3, .kadence-column15411_71e16f-d6 h4, .kadence-column15411_71e16f-d6 h5, .kadence-column15411_71e16f-d6 h6{color:#ffffff;}.kadence-column15411_71e16f-d6 a{color:#ffffff;}.kadence-column15411_71e16f-d6 a:hover{color:#fec00f;}.kadence-column15411_71e16f-d6{position:relative;}@media all and (max-width: 1024px){.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15411_71e16f-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column15411_71e16f-d6 feature-box-academic\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-navigation16450-cpt-id{--kb-nav-dropdown-border-top-left-radius:0px;--kb-nav-dropdown-border-top-right-radius:0px;--kb-nav-dropdown-border-bottom-right-radius:0px;--kb-nav-dropdown-border-bottom-left-radius:0px;--kb-nav-dropdown-border-radius-top:0px;--kb-nav-dropdown-border-radius-right:0px;--kb-nav-dropdown-border-radius-bottom:0px;--kb-nav-dropdown-border-radius-left:0px;--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}.header-desktop-transparent .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}.item-is-stuck .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}.wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-link-color:#18284a;--kb-nav-top-link-background:#f3f3f3;--kb-nav-top-link-border-bottom:2px solid #ffffff;}.wp-block-kadence-navigation16450-cpt-id > .navigation > .menu-container > .menu{--kb-nav-margin-top:-15px;--kb-nav-margin-right:-15px;--kb-nav-margin-left:-15px;}@media all and (max-width: 1024px){.wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);--kb-nav-top-link-border-bottom:2px solid #ffffff;}}@media all and (max-width: 1024px){.header-tablet-transparent .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}}@media all and (max-width: 1024px){.item-is-stuck .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}}@media all and (max-width: 767px){.wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);--kb-nav-top-link-border-bottom:2px solid #ffffff;}.header-mobile-transparent .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}.item-is-stuck .wp-block-kadence-navigation16450-cpt-id{--kb-nav-top-not-last-link-border-right:var(--kb-nav-link-border-right);}}<\/style><div class=\"wp-block-kadence-navigation16450-cpt-id kb-nav-desktop-horizontal-layout-standard kb-nav-tablet-horizontal-layout-standard kb-nav-mobile-horizontal-layout-standard navigation-desktop-layout-fill-stretch-false navigation-tablet-layout-fill-stretch-false navigation-mobile-layout-fill-stretch-false navigation-desktop-orientation-vertical navigation-tablet-orientation-vertical navigation-mobile-orientation-vertical wp-block-kadence-navigation\" data-scroll-spy=\"\"><nav class=\"navigation navigation-desktop-style-standard navigation-tablet-style-standard navigation-mobile-style-standard navigation-desktop-dropdown-animation-none navigation-tablet-dropdown-animation-none navigation-mobile-dropdown-animation-none navigation-desktop-collapse-sub-menus-true navigation-tablet-collapse-sub-menus-true navigation-mobile-collapse-sub-menus-true navigation-desktop-parent-toggles-menus-false navigation-tablet-parent-toggles-menus-false navigation-mobile-parent-toggles-menus-false navigation-desktop-parent-active-false navigation-tablet-parent-active-false navigation-mobile-parent-active-false\"><div class=\"menu-container\"><ul class=\"kb-navigation menu collapse-sub-nav-desktop-true collapse-sub-nav-tablet-true collapse-sub-nav-mobile-true\">\n<style>.kb-nav-link-ij4ugyqop > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-ij4ugyqop > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-ij4ugyqop menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/\"><strong>Radiation Oncology Home &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-wmg0g2wzr > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-wmg0g2wzr > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-wmg0g2wzr menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/catalog.virginiawestern.edu\/preview_program.php?catoid=24&#038;poid=3392&#038;returnto=2552\"><strong>Curriculum &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-2ehr3ukj8 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-2ehr3ukj8 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-2ehr3ukj8 menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/wp-content\/uploads\/sites\/31\/2025\/06\/RadiationOncologyChecklist.pdf\"><strong>Admission Requirements (PDF) &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-75c1kff55 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-75c1kff55 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-75c1kff55 menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/apply\/\"><strong>Apply Now &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-69cr2ncmp > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-69cr2ncmp > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-69cr2ncmp menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/cost\/\"><strong>Estimated Cost &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-be7ojeimc > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-be7ojeimc > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-be7ojeimc menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/\"><strong>Grading &amp; Clinical Requirements &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-ntzmv8h85 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-ntzmv8h85 > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-ntzmv8h85 menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/faq\/\"><strong>Frequently Asked Questions &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-zzxlhc7ep > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-zzxlhc7ep > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-zzxlhc7ep menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/forms\/\"><strong>Application Forms &amp; Resources &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-y8v9so9dh > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-y8v9so9dh > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-y8v9so9dh menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/joint-venture\/\"><strong>Joint Venture with NVCC &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-mlgrwg6xt > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-mlgrwg6xt > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-mlgrwg6xt menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/learning-outcomes\/\"><strong>Student Learning Outcomes &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-vpr759dgt > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-vpr759dgt > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-vpr759dgt menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/program-effectiveness-data\/\"><strong>Program Effectiveness Data &gt;<\/strong><\/a><\/div><\/li>\n\n<style>.kb-nav-link-wvf8nvghv > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-highlight-order:3;--kb-nav-link-highlight-icon-order:3;}.kb-nav-link-wvf8nvghv > .kb-link-wrap.kb-link-wrap.kb-link-wrap.kb-link-wrap{--kb-nav-link-media-max-width:px;}<\/style><li class=\"wp-block-kadence-navigation-link kb-nav-link-wvf8nvghv menu-item wp-block-kadence-navigation-link\"><div class=\"kb-link-wrap\"><a class=\"kb-nav-link-content\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/essential-functions\/\"><strong>Essential Functions &gt;<\/strong><\/a><\/div><\/li>\n<\/ul><\/div><\/nav><\/div>\n\n\n<h3 class=\"wp-block-heading\">Program Cost &amp; Length<\/h3>\n\n\n\n<p><strong>Est. Tuition*:<\/strong> $<span id=\"tuition\"><\/span><br><strong>Program Length:<\/strong> 2 Years<br><strong>Credits: <\/strong><span id=\"hours\">72<\/span><\/p>\n\n\n<div class=\"disclaimer\"><p>*Estimated cost reflects in-state rate and is subject to change. <a href=\"https:\/\/www.virginiawestern.edu\/pay\/cost-of-attendance\/\">Click here for the cost of attendance for financial aid<\/a>.<\/p><\/div>\n\n\n<h3>Health Professions Advising<\/h3>\n<p><i class=\"fa fa-envelope\" title=\"email\"><\/i> <a href=\"mailto:healthprofessions@virginiawestern.edu\">healthprofessions@virginiawestern.edu<\/a><br \/>\n<i class=\"fa fa-map-marker\" title=\"location\"><\/i>\u00a0Fralin Center HP339<br \/>\n<strong>New Students:\u00a0<\/strong>Chapman Hall<br \/>\n<i class=\"fa fa-phone-alt\" title=\"phone number\"><\/i>\u00a0540-857-7341 or 540-857-6644<br \/>\n<strong>Fax:<\/strong> 540-857-6640<\/p>\n\n\n\n\n<h3 class=\"wp-block-heading\">Program Head<\/h3>\n\n\n\n<p><strong>Tillie Conner, MS, RT(R)(T)<\/strong><br \/>\n<em>Director and Associate Professor of Radiation Oncology<\/em><\/p>\n<p>A.A.S. &#8211; Virginia Western Community College, 1981<br \/>\nB.A. &#8211; Mary Baldwin College, 1990<br \/>\nM.S.Ed. &#8211; Virginia Polytechnic University, 2002<\/p>\n\n\n\n<h3>Have Questions? Contact Us<\/h3>\n<p><i class=\"fa fa-envelope\" title=\"email\"><\/i>\u00a0<a href=\"mailto:enroll@virginiawestern.edu\">enroll@virginiawestern.edu<\/a><br \/>\n<i class=\"fa fa-map-marker\" title=\"location\"><\/i> Chapman Hall<br \/>\n<i class=\"fa fa-phone-alt\" title=\"phone number\"><\/i> <a href=\"tel:855-874-6690\">855-874-6690<\/a><\/p>\n\n\n\n<p class=\"school\">School of Health Professions<\/p>\n\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box15411_c56ead-89 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box15411_c56ead-89 .kt-blocks-info-box-link-wrap{border-top:3px solid #ffffff;border-right:3px solid #ffffff;border-bottom:3px solid #ffffff;border-left:3px solid #ffffff;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;background:#53c6d6;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box15411_c56ead-89 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box15411_c56ead-89 .kt-info-svg-icon-flip, .kt-info-box15411_c56ead-89 .kt-blocks-info-box-number{font-size:35px;}.kt-info-box15411_c56ead-89 .kt-blocks-info-box-media{color:#000000;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-info-box15411_c56ead-89 .kt-infobox-textcontent p.kt-blocks-info-box-title{color:#000000;font-family:-apple-system,BlinkMacSystemFont,u0022Segoe UIu0022,Roboto,Oxygen-Sans,Ubuntu,Cantarell,u0022Helvetica Neueu0022,sans-serif, u0022Apple Color Emojiu0022, u0022Segoe UI Emojiu0022, u0022Segoe UI Symbolu0022;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box15411_c56ead-89 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#000000;}.wp-block-kadence-infobox.kt-info-box15411_c56ead-89 .kt-blocks-info-box-text{font-weight:400;}.kt-info-box15411_c56ead-89 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box15411_c56ead-89 .kt-blocks-info-box-link-wrap{border-top:3px solid #ffffff;border-right:3px solid #ffffff;border-bottom:3px solid #ffffff;border-left:3px solid #ffffff;}}@media all and (max-width: 767px){.kt-info-box15411_c56ead-89 .kt-blocks-info-box-link-wrap{border-top:3px solid #ffffff;border-right:3px solid #ffffff;border-bottom:3px solid #ffffff;border-left:3px solid #ffffff;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box15411_c56ead-89 feature-box-light\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_info-circle kt-info-svg-icon\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119.043 8 8 119.083 8 256c0 136.997 111.043 248 248 248s248-111.003 248-248C504 119.083 392.957 8 256 8zm0 110c23.196 0 42 18.804 42 42s-18.804 42-42 42-42-18.804-42-42 18.804-42 42-42zm56 254c0 6.627-5.373 12-12 12h-88c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h12v-64h-12c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h64c6.627 0 12 5.373 12 12v100h12c6.627 0 12 5.373 12 12v24z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-title\">DID YOU KNOW?<\/p><p class=\"kt-blocks-info-box-text\"><p>This program is eligible for G3 funding assistance!\u00a0<a href=\"https:\/\/www.virginiawestern.edu\/freecollege\/\">Click here for more information and to contact an advisor<\/a>.<\/p>\n<\/p><\/div><\/span><\/div>\n\n\n<!-- Radiation Oncology -->\r\n  <div id=\"program-widget-deaaf6-wrapper\" style=\"height:100%\" >\r\n  <script type=\"text\/javascript\" src=\"https:\/\/widget.emsicc.com\/scripts.js\"><\/script>\r\n  <script> generateWidget({clientId:'virginiawestern',hasAllLocations:'false',hasCareerList:'true',hasEmployment:'true',hasImages:'true',hasJobOpenings:'true',hasNationalData:'true',hasOutlook:'true',hasSkills:'false',hasVisitButton:'true',hasWages:'true',id:'program-widget-deaaf6',isHourlyWage:'false',labelSet:'default',locationName:'Roanoke%2C%20VA',orderCareersBy:'None',primaryColor:'%2318284a',programs:'vw0083', \r\n  title:'virginiawestern widget',visitButtonColor:'%230053a5',headingText:'Potential%20Careers%20%26%20Labor%20Market%20Info' })\r\n  <\/script>\r\n  <\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Grading Information Students must maintain a grade of C or better in all program elective courses and all Radiation Oncology courses, and an overall GPA of 2.0 to continue in the program and graduate. All didactic Radiation Oncology classes require a 77 average to remain in the program. All clinical courses require an 81 overall&hellip; <a class=\"continue\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/\">Continue Reading<span> Grading &amp; Clinical Requirements<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":15388,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-15411","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western<\/title>\n<meta name=\"description\" content=\"Radiation Oncology grading information and clinical requirements\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western\" \/>\n<meta property=\"og:description\" content=\"Radiation Oncology grading information and clinical requirements\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/\" \/>\n<meta property=\"og:site_name\" content=\"Programs &amp; Training at Virginia Western\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T20:18:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/grading-clinical\\\/\",\"url\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/grading-clinical\\\/\",\"name\":\"Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/#website\"},\"datePublished\":\"2025-06-13T18:45:46+00:00\",\"dateModified\":\"2026-03-17T20:18:21+00:00\",\"description\":\"Radiation Oncology grading information and clinical requirements\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/grading-clinical\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/grading-clinical\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/grading-clinical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Healthcare\",\"item\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Radiation Oncology\",\"item\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/health-professions\\\/radiation-oncology\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Grading &amp; Clinical Requirements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/#website\",\"url\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/\",\"name\":\"Programs &amp; Training at Virginia Western\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.virginiawestern.edu\\\/academics\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western","description":"Radiation Oncology grading information and clinical requirements","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/","og_locale":"en_US","og_type":"article","og_title":"Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western","og_description":"Radiation Oncology grading information and clinical requirements","og_url":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/","og_site_name":"Programs &amp; Training at Virginia Western","article_modified_time":"2026-03-17T20:18:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/","url":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/","name":"Grading &amp; Clinical Requirements - Programs &amp; Training at Virginia Western","isPartOf":{"@id":"https:\/\/www.virginiawestern.edu\/academics\/#website"},"datePublished":"2025-06-13T18:45:46+00:00","dateModified":"2026-03-17T20:18:21+00:00","description":"Radiation Oncology grading information and clinical requirements","breadcrumb":{"@id":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/grading-clinical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.virginiawestern.edu\/academics\/"},{"@type":"ListItem","position":2,"name":"Healthcare","item":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/"},{"@type":"ListItem","position":3,"name":"Radiation Oncology","item":"https:\/\/www.virginiawestern.edu\/academics\/health-professions\/radiation-oncology\/"},{"@type":"ListItem","position":4,"name":"Grading &amp; Clinical Requirements"}]},{"@type":"WebSite","@id":"https:\/\/www.virginiawestern.edu\/academics\/#website","url":"https:\/\/www.virginiawestern.edu\/academics\/","name":"Programs &amp; Training at Virginia Western","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.virginiawestern.edu\/academics\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/pages\/15411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/comments?post=15411"}],"version-history":[{"count":0,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/pages\/15411\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/pages\/15388"}],"wp:attachment":[{"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/media?parent=15411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/categories?post=15411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virginiawestern.edu\/academics\/wp-json\/wp\/v2\/tags?post=15411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}